{"id":7139,"date":"2020-01-20T11:09:00","date_gmt":"2020-01-20T10:09:00","guid":{"rendered":"https:\/\/www.fluentis.com\/?p=7139"},"modified":"2023-09-20T11:14:54","modified_gmt":"2023-09-20T09:14:54","slug":"trends-tecnologici-2020","status":"publish","type":"post","link":"https:\/\/www.fluentis.com\/it\/blog\/trends-tecnologici-2020\/","title":{"rendered":"I Top 10 Trends Tecnologici Strategici per il 2020"},"content":{"rendered":"\n<p>Sicurezza dell\u2019Intelligenza Artificiale, Cloud distribuito, Iperautomazione, Multiexperience, Autonomous Things, Tracciabilit\u00e0 e Trasparenza sono alcuni dei trend tecnologici che guideranno la digital disruption nel 2020 e creeranno opportunit\u00e0 per le organizzazioni che saranno in grado di coglierli e declinarli. Vi presentiamo di seguito la lista dei 10 top trend presentati da <a href=\"https:\/\/www.gartner.com\/smarterwithgartner\/gartner-top-10-strategic-technology-trends-for-2020\/\" target=\"_blank\" rel=\"noreferrer noopener\">Gartner<\/a> in occasione del Symposium 2019 a Barcellona, strutturati attorno all\u2019idea di \u201csmart spaces incentrati sulle persone\u201d, in altre parole considereremo come queste tecnologie influenzeranno le persone (ad es. clienti, dipendenti) e i luoghi in cui vivono (ad es. casa, ufficio, auto).<\/p>\n\n\n\n<p>I trend tecnologici strategici hanno in s\u00e8 il potenziale sia di creare opportunit\u00e0 che di innescare cambiamenti significativi. I leader dell\u2019Enterprise Architecture e dell\u2019IT aziendale dovrebbero valutare queste tendenze per determinare quali trend possono giocare un ruolo cruciale nelle loro strategie di innovazione, per migliorare processi, prodotti e modelli di business esistenti, o crearne di nuovi.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1009\" height=\"475\" src=\"https:\/\/www.fluentis.com\/wp-content\/uploads\/2023\/09\/Top-10-Technology-Trends-Gartner.jpg\" alt=\"\" class=\"wp-image-7146\" srcset=\"https:\/\/www.fluentis.com\/wp-content\/uploads\/2023\/09\/Top-10-Technology-Trends-Gartner.jpg 1009w, https:\/\/www.fluentis.com\/wp-content\/uploads\/2023\/09\/Top-10-Technology-Trends-Gartner-300x141.jpg 300w, https:\/\/www.fluentis.com\/wp-content\/uploads\/2023\/09\/Top-10-Technology-Trends-Gartner-768x362.jpg 768w\" sizes=\"auto, (max-width: 1009px) 100vw, 1009px\" \/><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">People-Centric Trends<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Trend n. 1 &#8211; <\/strong><strong>Iperautomazione<\/strong><\/h3>\n\n\n\n<p>L\u2019automazione utilizza la tecnologia per automatizzare le attivit\u00e0 che un tempo richiedevano&nbsp; l\u2019intervento dell\u2019uomo. L\u2019iperautomazione si occupa dell\u2019applicazione di tecnologie avanzate, tra cui l\u2019intelligenza artificiale (AI) e l\u2019apprendimento automatico (ML), per automatizzare sempre pi\u00f9 i processi e \u201caumentare\u201d gli esseri umani. L\u2019iperautomazione si estende attraverso una gamma di strumenti che possono essere automatizzati, ma si riferisce anche alla raffinatezza dell\u2019automazione (finalizzata ad esempio ad attivit\u00e0 come scoprire, analizzare, progettare, misurare, monitorare, rivalutare). Poich\u00e9 nessun singolo strumento pu\u00f2 sostituire gli esseri umani, l\u2019iperautomazione oggi comporta una combinazione di strumenti, tra cui l\u2019automazione dei processi robotici (RPA), il software di gestione aziendale intelligente (iBPMS) e l\u2019Artificial Intelligence, con l\u2019obiettivo di prendere sempre pi\u00f9 decisioni basate sull\u2019intelligenza artificiale.<\/p>\n\n\n\n<p>Sebbene non sia l\u2019obiettivo principale, l\u2019iperautomazione si traduce spesso nella creazione di un Digital Twin dell\u2019organizzazione (DTO), che consente alle organizzazioni di visualizzare il modo in cui funzioni, processi e KPI interagiscono per portare valore. Il DTO diventa quindi pa rte integrante del processo di iperautomazione, fornendo informazioni continue e in tempo reale sull\u2019organizzazione e guidando importanti opportunit\u00e0 commerciali.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Trend n. 2<\/strong> &#8211; <strong>Multiexperience<\/strong><\/h3>\n\n\n\n<p>La Multiexperience sostituisce il concetto di \u201cpersone esperte in tecnologia\u201d con quello di \u201ctecnologie esperte dei comportamenti umani\u201d. Cambia la prospettiva, l\u2019idea tradizionale di computer si evolve da un unico punto di interazione per includere interfacce multisensoriali e multitouchpoint come dispositivi indossabili e sensori avanzati per computer.<\/p>\n\n\n\n<p>Domino\u2019s Pizza \u00e8 uno degli esempi pi\u00f9 noti delle aziende che hanno investito maggiormente in una piattaforma multiexperience, andando molto al di l\u00e0 di una semplice app mobile per ordinare le pizze: la multiexperience offerta ai propri clienti include applicazioni che accedono a smart speakers, una \u201cpizza tracker\u201d app per tracciare in tempo reale dove si trova la propria pizza, l\u2019uso di veicoli autonomi e droni per la consegna, e molto altro.<\/p>\n\n\n\n<p>In futuro questo trend diventer\u00e0 quella che viene definita un\u2019esperienza ambientale, ma attualmente la multiexperience si concentra su esperienze immersive che utilizzano realt\u00e0 aumentata (AR), virtuale (VR), realt\u00e0 mista (MR), interfacce uomo-macchina multicanale e tecnologie di rilevamento. La combinazione di queste tecnologie pu\u00f2 essere utilizzata per una semplice sovrapposizione di realt\u00e0 aumentata o un\u2019esperienza di realt\u00e0 Virtuale completamente immersiva.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Trend n. 3<\/strong> &#8211; <strong>Democratizzazione<\/strong><\/h3>\n\n\n\n<p>Democratizzare la tecnologia significa fornire alle persone un facile accesso a competenze tecniche o specifiche senza una formazione estesa (e costosa). I professionisti non IT hanno sempre pi\u00f9 accesso a potenti strumenti e sistemi esperti che li abilitano a sfruttare e applicare funzionalit\u00e0 specializzate al di l\u00e0 delle proprie competenze e formazione. La democratizzazione si concentra su 4 aree chiave \u2013 sviluppo di applicazioni, analisi dei dati, progettazione e knowledge \u2013 ed \u00e8 spesso definita come \u201ccitizen access\u201d, fenomeno che ha portato alla crescita di figure come i citizen data scientist e i citizen programmers.<\/p>\n\n\n\n<p>Per fare un esempio, la democratizzazione consentirebbe agli sviluppatori di generare modelli di dati senza avere le competenze di un data scientist. Come? Facendo affidamento sullo sviluppo basato sull\u2019Intelligenza Artificiale per generare codice e automatizzare i test.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Trend n. 4<\/strong> &#8211; <strong>Human Augmentation<\/strong><\/h3>\n\n\n\n<p>La Human Augmentation si riferisce all\u2019uso della tecnologia per migliorare le esperienze cognitive e fisiche di una persona. Il termine Human Augmentation evoca visioni di cyborg futuristici, ma in realt\u00e0 non \u00e8 nulla di cos\u00ec nuovo: gli esseri umani hanno \u201caumentato\u201d parti del loro corpo per centinaia di anni. Occhiali, apparecchi acustici e protesi si sono evoluti in impianti cocleari e dispositivi indossabili. La chirurgia laser per correggere i problemi visivi ad esempio \u00e8 diventata qualcosa di molto comune.<br>E se gli scienziati fossero ora in grado di \u201caumentare\u201d il cervello per incrementare la memoria o impiantare un chip per decodificare i modelli neurali? Se gli esoscheletri diventassero un\u2019uniforme standard per i lavoratori, consentendo loro di sollevare pesi sovrumani? E se i medici potessero impiantare sensori per tracciare il modo in cui i farmaci agiscono all\u2019interno del corpo?<br>La tecnologia sta andando ben oltre la capacit\u00e0 di sostituire una capacit\u00e0 umana, portando inevitabilmente con s\u00e9 una serie di implicazioni culturali ed etiche.<\/p>\n\n\n\n<p>Il modo in cui questi cambiamenti avranno un impatto sul mondo e sul business rende la Human Augmentation uno dei principali trend tecnologici strategici che porter\u00e0 un impatto significativo nei prossimi 5 o 10 anni.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Trend n. 5<\/strong> &#8211; <strong>Trasparenza e Tracciabilit\u00e0<\/strong><\/h3>\n\n\n\n<p>L\u2019Etica Digitale e la Privacy sono temi sempre pi\u00f9 scottanti per individui, organizzazioni e governi. I consumatori sono sempre pi\u00f9 consapevoli che le loro informazioni personali sono preziose e richiedono un controllo al riguardo. Le organizzazioni riconoscono il rischio crescente di proteggere e gestire i dati personali e i governi stanno implementando leggi molto rigorose per garantire che ci\u00f2 avvenga.<br>L\u2019Intelligenza Artificiale e l\u2019Apprendimento Automatico sono sempre pi\u00f9 utilizzati per prendere decisioni al posto degli esseri umani e questo non fa che aumentare la crisi di fiducia a cui stiamo assistendo.<br>Etica Digitale, Privacy dei dati, la necessit\u00e0 di un\u2019Intelligenza Artificiale spiegabile ed etica, sono tutti temi critici che sono emersi per cercare di trovare una risposta alla questa crisi in atto.<br>Bisogna iniziare ad essere trasparenti su come usiamo i dati, su come costruiamo i nostri modelli di Intelligenza Artificiale e come poi li usiamo.<br>Trasparenza e Tracciabilit\u00e0 sono elementi fondamentali per supportare le esigenze di Etica Digitale e Privacy.<\/p>\n\n\n\n<p>La Trasparenza e la Tracciabilit\u00e0 non sono un singolo prodotto o una singola azione. Si tratta di una serie di azioni, tecnologie e pratiche di supporto progettate per soddisfare i requisiti normativi, sancire un approccio etico all\u2019uso dell\u2019AI e di altre tecnologie avanzate e riacquistare fiducia agli occhi dei nostri interlocutori.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Smart Spaces Trends<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Trend n. 6<\/strong> &#8211; <strong>Empowered Edge<\/strong><\/h3>\n\n\n\n<p>Edge computing \u00e8 una topologia in cui l\u2019elaborazione delle informazioni e la raccolta e consegna dei contenuti sono pi\u00f9 vicine alle fonti di informazioni, secondo il presupposto che mantenere il traffico locale e distribuito ridurr\u00e0 la latenza. Con la tecnologia Empowered Edge i dispositivi IoT stanno aumentando, gettando le basi per gli smart spaces, avvicinando le applicazioni e i servizi chiave alle persone e ai dispositivi che li utilizzano.<br>Per esempio, nel contesto delle Conversational Platform molti di questi sistemi oggi si affidano a servizi remoti basati su Cloud: si auspica che nel prossimo futuro i processi conversational si svolgeranno nell\u2019Edge, non nel Central Cloud.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Trend n. 7<\/strong> &#8211; <strong>Distributed Cloud<\/strong><\/h3>\n\n\n\n<p>Il Cloud Distribuito si riferisce alla distribuzione di servizi Public Cloud in posizioni esterne ai data center fisici del provider cloud, ma che sono ancora controllati dal provider. Nel Cloud Distribuito, il provider Cloud \u00e8 responsabile di tutti gli aspetti dell\u2019architettura, della consegna, delle operazioni, della governance e degli aggiornamenti del servizio Cloud.<br>L\u2019evoluzione dal Public Cloud Centralizzato al Public Cloud Distribuito inaugura una nuova era del Cloud computing.<\/p>\n\n\n\n<p>Il Cloud Distribuito consente di localizzare i data center ovunque. Ci\u00f2 risolve sia problemi tecnici come la latenza sia sfide normative come la sovranit\u00e0 dei dati. Offre inoltre i vantaggi di un servizio Public Cloud insieme ai vantaggi di un Private Cloud locale.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Trend n. 8<\/strong> &#8211; <strong>Autonomous Things<\/strong><\/h3>\n\n\n\n<p>Autonomous Things, o gli oggetti autonomi, che includono droni, robot, navi ed elettrodomestici, sfruttano l\u2019Intelligenza Artificiale per svolgere compiti normalmente svolti dagli esseri umani. Questa tecnologia opera su uno spettro di intelligenza che va dal semiautonomo al completamente autonomo e in una variet\u00e0 di ambienti tra cui aria, mare e terra.<\/p>\n\n\n\n<p>Mentre gli oggetti autonomi attualmente esistono principalmente in ambienti controllati, come in una miniera o in un magazzino, si stanno evolvendo per essere utilizzati in futuro in spazi pubblici. Gli oggetti autonomi passeranno anche da sciami autonomi a sciami collaborativi, come gli sciami di droni usati durante le Olimpiadi invernali del 2018.<\/p>\n\n\n\n<p>Tuttavia, gli oggetti autonomi non possono sostituire il cervello umano e operare nel modo pi\u00f9 efficace con uno scopo ben definito.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Trend n. 9<\/strong> &#8211; <strong>Practical Blockchain<\/strong><\/h3>\n\n\n\n<p>Blockchain \u00e8 una sorta di libro mastro distribuito, un elenco in espansione cronologicamente ordinato di record transazionali irrevocabili con firma crittografica condivisi da tutti i partecipanti in una rete.<br>La blockchain consente alle parti di risalire agli impianti e alla loro origine, il che \u00e8 vantaggioso per gli asset tradizionali, ma spiana anche la strada per altri usi, come ad esempio rintracciare malattie di origine alimentare al fornitore originale. Inoltre, consente a 2 o pi\u00f9 parti che non si conoscono di interagire in sicurezza in un ambiente digitale e scambiare valore senza la necessit\u00e0 di un\u2019autorit\u00e0 centralizzata.<br>Il modello blockchain completo include 5 elementi: un libro mastro condiviso e distribuito, un libro mastro immutabile e tracciabile, la crittografia, la tokenizzazione e un meccanismo di consenso pubblico distribuito. Tuttavia, la blockchain rimane immatura per le implementazioni aziendali a causa di una serie di problemi tecnici tra cui scarsa scalabilit\u00e0 e interoperabilit\u00e0.<\/p>\n\n\n\n<p>In futuro, il modello blockchain completo avr\u00e0 il potenziale di trasformare le industrie e, infine, l\u2019economia, perch\u00e8 tecnologie complementari come l\u2019AI e l\u2019IoT inizieranno a integrarsi insieme alla blockchain. Questo espande la tipologia di partecipanti e includer\u00e0 le macchine, che saranno in grado di scambiare una variet\u00e0 di attivit\u00e0 \u2013 dal denaro agli immobili. Ad esempio, un\u2019auto sarebbe in grado di negoziare i prezzi assicurativi direttamente con la compagnia assicurativa sulla base dei dati raccolti dai suoi sensori.<\/p>\n\n\n\n<p>Blockchain, che sta gi\u00e0 apparendo in progetti sperimentali e di piccola portata, sar\u00e0 completament&nbsp; scalabile entro il 2023.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Trend n. 10<\/strong> &#8211; <strong>AI Security<\/strong><\/h3>\n\n\n\n<p>Nel corso dei prossimi 5 anni, l\u2019Intelligenza Artificiale, e in particolare il Machine Learning, sar\u00e0 applicata per aumentare il processo decisionale umano attraverso un\u2019ampia gamma di casi d\u2019uso. Allo stesso tempo, inevitabilmente, ci sar\u00e0 un enorme aumento dei potenziali punti di attacco con IoT, Cloud Computing, microservizi e sistemi altamente connessi in smart spaces. Sebbene ci\u00f2 crei grandi opportunit\u00e0 consentendo l\u2019iperautomazione e sfruttando gli oggetti autonomi per raggiungere una trasformazione aziendale, si creeranno anche nuove e significative sfide per il team deputato alla sicurezza aziendale.<\/p>\n\n\n\n<p>Di seguito elenchiamo i 3 temi principali per la sicurezza dell\u2019Intelligenza Artificiale:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Proteggere i sistemi basati sull\u2019Intelligenza Artificiale: protezione dei training data AI, training pipelines e modelli ML.<\/li>\n\n\n\n<li>Sfruttare l\u2019Intelligenza Artificiale per migliorare la difesa della sicurezza: usare l\u2019apprendimento automatico per comprendere schemi, scoprire attacchi e automatizzare parti dei processi di sicurezza informatica.<\/li>\n\n\n\n<li>Anticipare l\u2019uso scorretto dell\u2019AI da parte degli aggressori: identificare gli attacchi e difendersi da essi<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Sicurezza dell\u2019Intelligenza Artificiale, Cloud distribuito, Iperautomazione, Multiexperience, Autonomous Things, Tracciabilit\u00e0 e Trasparenza sono alcuni dei trend tecnologici che [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7141,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-7139","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trend-tecnologici"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.fluentis.com\/it\/wp-json\/wp\/v2\/posts\/7139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fluentis.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fluentis.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fluentis.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fluentis.com\/it\/wp-json\/wp\/v2\/comments?post=7139"}],"version-history":[{"count":3,"href":"https:\/\/www.fluentis.com\/it\/wp-json\/wp\/v2\/posts\/7139\/revisions"}],"predecessor-version":[{"id":7151,"href":"https:\/\/www.fluentis.com\/it\/wp-json\/wp\/v2\/posts\/7139\/revisions\/7151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fluentis.com\/it\/wp-json\/wp\/v2\/media\/7141"}],"wp:attachment":[{"href":"https:\/\/www.fluentis.com\/it\/wp-json\/wp\/v2\/media?parent=7139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fluentis.com\/it\/wp-json\/wp\/v2\/categories?post=7139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fluentis.com\/it\/wp-json\/wp\/v2\/tags?post=7139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}